{"id":272,"count":1,"description":"","link":"https:\/\/egyptconcierge.travel\/index.php\/tag\/conspiracy-theories\/","name":"conspiracy theories","slug":"conspiracy-theories","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/egyptconcierge.travel\/index.php\/wp-json\/wp\/v2\/tags\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egyptconcierge.travel\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/egyptconcierge.travel\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/egyptconcierge.travel\/index.php\/wp-json\/wp\/v2\/posts?tags=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}